{"id":13323,"date":"2021-02-05T15:08:46","date_gmt":"2021-02-05T15:08:46","guid":{"rendered":"https:\/\/hosting.uantwerpen.be\/globalpps4\/?page_id=13323"},"modified":"2026-05-06T15:14:34","modified_gmt":"2026-05-06T15:14:34","slug":"materiales-para-congresos","status":"publish","type":"page","link":"https:\/\/www.global-pps.com\/es\/congress-materials\/","title":{"rendered":"Materiales del Congreso"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"13323\" class=\"elementor elementor-13323\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"ob-is-breaking-bad elementor-section elementor-top-section elementor-element elementor-element-6944a085 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6944a085\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ob_bbad_use_it&quot;:&quot;yes&quot;,&quot;_ob_bbad_sssic_use&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1279ca56\" data-id=\"1279ca56\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;_ob_bbad_is_stalker&quot;:&quot;no&quot;,&quot;_ob_teleporter_use&quot;:false,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-597a199 ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"597a199\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\nMateriales del Congreso<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-786c1c4 ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"786c1c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_postman_use&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-canvas-width=\"400.25322514580404\"><p>Los resultados de Global-PPS se han comunicado en diversos congresos.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"ob-is-breaking-bad elementor-section elementor-top-section elementor-element elementor-element-42fbf2e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"42fbf2e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ob_bbad_use_it&quot;:&quot;yes&quot;,&quot;_ob_bbad_sssic_use&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4eadd7ee\" data-id=\"4eadd7ee\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ob_bbad_is_stalker&quot;:&quot;no&quot;,&quot;_ob_teleporter_use&quot;:false,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c7c2e82 ob-has-background-overlay elementor-widget elementor-widget-toggle\" data-id=\"2c7c2e82\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7461\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-7461\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Congresses 2026<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7461\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-7461\"><p><a href=\"https:\/\/www.eccmid.org\/\"><strong>ESCMID Global 2026, Munich<\/strong><\/a><\/p><p>The Global-PPS delegates presented four posters at ESCMID Global, sharing their latest research findings and insights:<\/p><ul><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2026\/04\/ESCMID-2026_P3004_JUG-pages-2.pdf\">The global point prevalence survey (Global-PPS): trends of antimicrobial use in adult patients in the Philippines 2017-2024<\/a>\u00a0\u2013 Presenter: Jemelyn Garcia<\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2026\/04\/ESCMID-2026-Global-PPS-and-SAP-poster.pdf\">Global point prevalence survey of antimicrobial consumption and resistance (Global-PPS): monitoring effectiveness of an EMR-assisted pre-authorisation requirement for non-guideline compliant surgical antimicrobial prophylaxis prescriptions at a tertiary hospital in the Philippines<\/a>\u00a0\u2013 Presenter: Maria Charmian Hufano<\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2026\/04\/ESCMID-Poster-Operationalising-AWaRe-QI-7-4-2026.pdf\">Operationalising AWaRe antibiotic quality indicators using existing antimicrobial use surveillance data<\/a>\u00a0\u2013\u00a0Presenter:\u00a0Hossam Almadhoon<\/li><li>\u00a0<a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2026\/04\/ESCMID26-E0646-ePOSTER_FINAL.pdf\">Antimicrobial prescribing in five primary healthcare centres in northern Syria: a Global-PPS based period prevalence survey<\/a>\u00a0\u2013 Presenter: Fatima Abdo<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7462\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-7462\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Congresos 2025<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7462\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-7462\"><p><a href=\"https:\/\/medmycol.be\/bsham-annual-symposium-2025\/\"><strong>Simposio anual de la BSHAM 2025<\/strong><\/a><\/p><p>Descargue el cartel de Global-PPS:<\/p><ul><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2025\/10\/BSHAM2025.pptx\">Consumo de antif\u00fangicos en B\u00e9lgica entre 2015 y 2023<\/a><\/li><\/ul><p><strong><a href=\"https:\/\/www.siz.be\/siz-be-annual-meeting\">Simposio conjunto SIZ - BVIKM 2025<\/a><\/strong><\/p><p>Descargue el cartel de Global-PPS:<\/p><ul><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2025\/10\/AntifungalconsumptionICU_BVIKM2025.pdf\">Indicaciones y patrones de consumo de terapia antif\u00fangica en las UCI belgas entre 2015 y 2022<\/a><\/li><\/ul><p><a href=\"https:\/\/www.timm2025.org\/\"><strong>12\u00aa Tendencia en Micolog\u00eda M\u00e9dica<\/strong><\/a><\/p><p>Descargue el cartel de Global-PPS:<\/p><ul><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2025\/10\/TIMM2025.pdf\">Consumo de antif\u00fangicos en B\u00e9lgica entre 2015 y 2024<\/a><\/li><\/ul><p><a href=\"https:\/\/www.icancongress.com\/home\/\"><strong><strong><strong>Congreso de la Red Africana de Control de Infecciones (ICAN)<\/strong><\/strong><\/strong><\/a><\/p><p>Descargue los carteles de Global-PPS:<\/p><ul><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2025\/07\/ICAN2025_poster_ANTIMALARIAL-LAGOS_drPhilipOshun.pdf\" target=\"_blank\" rel=\"noopener\">El Global-PPS para pacientes ambulatorios identifica puntos de acci\u00f3n clave para la administraci\u00f3n de antimicrobianos antimal\u00e1ricos entre los centros sanitarios de Lagos (Nigeria)<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2025\/07\/ICAN2025_poster_antimicrobial-AFRICA_drPhilipOshun.pdf\" target=\"_blank\" rel=\"noopener\">El Global-PPS para pacientes ambulatorios identifica puntos de acci\u00f3n clave para la administraci\u00f3n de antimicrobianos en los centros sanitarios de Nigeria, Burkina Faso y Togo.<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2025\/07\/ICAN2025_Poster_G-PPS-in-NG_profOyinOduyebo.pdf\" target=\"_blank\" rel=\"noopener\">Las tendencias longitudinales ponen de manifiesto la persistencia de los patrones de prescripci\u00f3n de antimicrobianos en los hospitales nigerianos<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2025\/07\/ICAN2025_Poster_G-PPS_Antoinette-Moolman.pdf\">Encuesta mundial de prevalencia puntual del consumo y la resistencia a los antimicrobianos (Global-PPS) en los servicios ambulatorios de un centro acad\u00e9mico de Gauteng<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2025\/07\/ICAN2025_poster_G-PPS_Dr-Sibongile-Kondowe.pdf\" target=\"_blank\" rel=\"noopener\">Patrones de uso de antibi\u00f3ticos en pacientes adultos de siete hospitales de Malawi<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2025\/07\/ICAN2025_poster_OutpatientGlobalPPS_AnneliesBoven.pdf\" target=\"_blank\" rel=\"noopener\">Un enfoque estandarizado para medir los datos de uso de antimicrobianos en pacientes ambulatorios: desarrollo y evaluaci\u00f3n de la Encuesta Global de Prevalencia Puntual en pacientes ambulatorios.<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2025\/07\/ICAN2025_poster_SP-in-Africa_AnnVersporten.pdf\" target=\"_blank\" rel=\"noopener\">Prescripci\u00f3n de profilaxis quir\u00fargica en hospitales africanos. Conclusiones de la encuesta mundial de prevalencia puntual sobre consumo y resistencia a los antimicrobianos.<\/a><\/li><\/ul><p><span data-olk-copy-source=\"MessageBody\">Descargar las presentaciones de la Sesi\u00f3n 3: Aplicaci\u00f3n de encuestas de prevalencia puntual para mejorar la administraci\u00f3n de antimicrobianos en el continente africano.<\/span><\/p><ul><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2025\/07\/AnnVersporten_Global-PPS_in-AfricanCountries_ICAN2025_session3.pdf\" target=\"_blank\" rel=\"noopener\">Global-PPS sobre consumo de antimicrobianos y vigilancia de las HAI en los pa\u00edses africanos. Trayectoria de armonizaci\u00f3n entre el Global-PPS y el WHO-PPS<\/a> (Ann Versporten)<\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2025\/07\/MaxenciaNabiryo_CPA-AMS-Experiences_with-Global-PPS_ICAN2025_session3.pdf\" target=\"_blank\" rel=\"noopener\">Mejora de la aplicaci\u00f3n internacional de la MGA con Global-PPS: la experiencia del programa SPARC<\/a> (Maxencia Nabiryo)<\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2025\/07\/ReshmaMisra-AMUandHAI-using-the-Global-PPS_in-KZN_South-Africa_ICAN2025_Session3.pdf\" target=\"_blank\" rel=\"noopener\">Prescripci\u00f3n de antimicrobianos y vigilancia de las infecciones relacionadas con la asistencia sanitaria en la provincia de KwaZulu Natal, Sud\u00e1frica<\/a> (Reshma Misra)<\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2025\/08\/PhilipOshun_OutpatientGlobal-PPSAMS-in-Lagos_Nigeria_ICAN2025_workshop.pdf\">Administraci\u00f3n de antimicrobianos en pacientes ambulatorios de Lagos basada en datos<\/a> (Philip Oshun)<\/li><\/ul><p><a href=\"https:\/\/www.eccmid.org\/\"><strong>ESCMID Global 2025, Viena<\/strong><\/a><\/p><p>Descargue los carteles de Global-PPS:<\/p><ul><li>Resultados del Global-PPS:<ul><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2025\/04\/ECSCMID-Global-2025_poster_OutpatientGlobalPPS_final.pdf\">Un enfoque normalizado para medir los datos de uso de antimicrobianos en pacientes ambulatorios: desarrollo y evaluaci\u00f3n de la encuesta mundial de prevalencia puntual en pacientes ambulatorios<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2025\/04\/ECSCMID-Global-2025_poster_PredictorsHospitalAMU_final3.pdf\">Identificaci\u00f3n de factores predictivos del uso de antibi\u00f3ticos: un estudio global de prevalencia puntual en 130 hospitales de B\u00e9lgica, Filipinas y Sud\u00e1frica<\/a><\/li><\/ul><\/li><li>Asociaciones globales-PPS:<ul><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2025\/04\/ECSCMID-Global-2025_ePoster-WHO.pdf\">Trayectoria de armonizaci\u00f3n de la Encuesta Global de Prevalencia (Global-PPS) y la WHO-PPS<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2025\/04\/ECSCMID-Global-2025_drive-AMS-poster_portrait_v4.pdf\">Implantaci\u00f3n de la administraci\u00f3n antimicrobiana hospitalaria en Europa mediante un enfoque de cambio de comportamiento basado en datos: conclusiones del proyecto drive-AMS de la UE<\/a><\/li><\/ul><\/li><li>Filipinas:<ul><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2025\/04\/ECSCMID-Global-2025-DR.-JUG-Final.pdf\">La encuesta mundial de prevalencia puntual (Global-PPS): indicadores de calidad para el uso de antimicrobianos en pacientes adultos en Filipinas, 2017-2023.<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2025\/04\/ECSCMID-Global-2025_poster_7year-SAP-prescribing-practices_final.pdf\">Implementaci\u00f3n de la administraci\u00f3n antimicrobiana en un hospital terciario filipino: vigilancia durante siete a\u00f1os de las pr\u00e1cticas de prescripci\u00f3n de profilaxis quir\u00fargica<\/a><\/li><\/ul><\/li><li>Proyecto ADILA:<ul><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2025\/04\/O-vs-E-poster-ECCMID-2025-V7.pdf\">Evaluaci\u00f3n comparativa del uso hospitalario de antibi\u00f3ticos en diez pa\u00edses: comparaci\u00f3n del uso emp\u00edrico observado frente al esperado seg\u00fan el libro de antibi\u00f3ticos AWaRe de la OMS.<\/a><\/li><\/ul><\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7463\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-7463\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Congresos 2024<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7463\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-7463\"><p><strong>ESCMID Global 2024 (antigua ECCMID), Barcelona<\/strong><\/p><p><a href=\"https:\/\/www.eccmid.org\/\" target=\"_blank\" rel=\"noopener\">Visite el sitio web<\/a><\/p><p>Descargue los carteles de Global-PPS:<\/p><ul><li><strong>Resultados del Global-PPS:<\/strong><ul><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2024\/05\/ECCMID2024-Poster-P2623_Annelies_final.pdf\" target=\"_blank\" rel=\"noopener\">Prescripci\u00f3n de antimicrobianos en salas de urgencias de B\u00e9lgica, Brasil, Canad\u00e1, Georgia y el Reino Unido: primeros resultados de la Encuesta mundial de prevalencia puntual del consumo y la resistencia a los antimicrobianos en pacientes ambulatorios.<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2024\/05\/ECCMID2024_poster_P266_Ines.pdf\" target=\"_blank\" rel=\"noopener\">Determinantes y oportunidades de la aplicaci\u00f3n de la administraci\u00f3n de antimicrobianos en hospitales de pa\u00edses de ingresos bajos y medios: un estudio cualitativo<\/a><\/li><\/ul><\/li><li><strong>Nigeria: <\/strong><ul><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2024\/05\/ECCMID-2024-Poster-P2676_Ubong.pdf\" target=\"_blank\" rel=\"noopener\">Encuesta mundial de prevalencia puntual del consumo y la resistencia a los antimicrobianos (Global-PPS): Resultados sobre la prescripci\u00f3n ambulatoria de antimicrobianos en Calabar (Nigeria)<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2024\/05\/Pfizer_NG.pdf\" target=\"_blank\" rel=\"noopener\">El primer resultado del m\u00f3dulo ambulatorio del Global-PPS identifica puntos de acci\u00f3n clave para la administraci\u00f3n antimicrobiana en diez centros sanitarios de Lagos (Nigeria).<\/a><\/li><\/ul><\/li><li><strong>Filipinas:<\/strong><ul><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2024\/05\/ECCMID2024_poster_P2701_Jemelyn.pdf\" target=\"_blank\" rel=\"noopener\">La encuesta de prevalencia puntual global (Global-PPS): profilaxis antimicrobiana quir\u00fargica en Filipinas de 2017 a 2022<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2024\/05\/ECCMID-2024_poster_P2673_Jay.pdf\" target=\"_blank\" rel=\"noopener\">Implementaci\u00f3n de la administraci\u00f3n de antimicrobianos en un hospital filipino de atenci\u00f3n terciaria: un an\u00e1lisis quinquenal de encuestas de prevalencia puntual repetidas para el seguimiento y la mejora de la calidad<\/a><\/li><\/ul><\/li><li><strong>Sud\u00e1frica:<\/strong> <a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2024\/05\/ECCMID2024_poster_P2681_Joanna.pdf\" target=\"_blank\" rel=\"noopener\">Prescripci\u00f3n de antimicrobianos en tres hospitales p\u00fablicos de la Sud\u00e1frica rural en 2023: resultados de la encuesta mundial de prevalencia puntual<\/a><\/li><li><strong>Ruanda:<\/strong> <a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2024\/05\/ECCMID2024_poster_P2634_Caroline.pdf\" target=\"_blank\" rel=\"noopener\">Comparaci\u00f3n de la prescripci\u00f3n de antimicrobianos entre un hospital de atenci\u00f3n terciaria belga y otro ruand\u00e9s mediante la herramienta Global Point Prevalence Survey (Global-PPS)<\/a><\/li><li><strong>Proyecto ADILA: <\/strong><ul><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2024\/05\/O-vs-E-analysis-ECCMID-poster_final.pdf\" target=\"_blank\" rel=\"noopener\">Niveles observados frente a niveles esperados de uso emp\u00edrico de antibi\u00f3ticos basados en el libro de antibi\u00f3ticos AWaRe de la OMS: una nueva herramienta de evaluaci\u00f3n comparativa.<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2024\/05\/04169_ECCMID_2024_used.pdf\" target=\"_blank\" rel=\"noopener\">\u00bfProporciona la formulaci\u00f3n antibi\u00f3tica estimaciones razonables del uso de antibi\u00f3ticos en los distintos sectores?<\/a><\/li><\/ul><\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7464\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-7464\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Congresos 2023<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7464\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-7464\"><p><strong>Simposios SBIMC-BVIKM<\/strong><\/p><p>Visite <a href=\"https:\/\/eur01.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fsbimc-bvikm.be%2Fen%2F&amp;data=05%7C01%7CLeandra.Reijsmeijer%40uantwerpen.be%7C9ded372792924a738a3c08dbe09ea226%7C792e08fb2d544a8eaf72202548136ef6%7C0%7C0%7C638350744694967245%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C3000%7C%7C%7C&amp;sdata=oxkYf8b3HwVsvMlSdOnPd2JMn%2Bhs23OIQtxZ3WvgprQ%3D&amp;reserved=0\" target=\"_blank\" rel=\"noopener\">aqu\u00ed<\/a> la p\u00e1gina web de la Sociedad Belga de Infectolog\u00eda y Microbiolog\u00eda Cl\u00ednica (SBIMC-BVIKM).<\/p><p>Lea el folleto de res\u00famenes : <a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2023\/11\/Abstract-Booklet-AMS-symposium.pdf\" target=\"_blank\" rel=\"noopener\">Administraci\u00f3n antimicrobiana: Integraci\u00f3n de teor\u00eda, pr\u00e1ctica y tecnolog\u00eda<\/a><\/p><p><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2023\/11\/BVIKM_antimycotics_antifungals-final.pdf\" target=\"_blank\" rel=\"noopener\">Descargar el cartel de Global-PPS<\/a> sobre las pautas de prescripci\u00f3n de antimic\u00f3ticos y antif\u00fangicos en B\u00e9lgica<\/p><p><strong>IP2023 Liverpool<\/strong><\/p><p><a href=\"https:\/\/eur01.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fip2023conference.net%2F&amp;data=05%7C01%7CLeandra.Reijsmeijer%40uantwerpen.be%7C51047812efb044a5ea6908dbca36f77d%7C792e08fb2d544a8eaf72202548136ef6%7C0%7C0%7C638326110284828794%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C3000%7C%7C%7C&amp;sdata=gmwnnJbc6fzB4Z3z3Zw68LyxzZNUhFhhBir2FVgV9ns%3D&amp;reserved=0\" target=\"_blank\" rel=\"noopener\">Visite el sitio web<\/a><\/p><p>Cartel de Global-PPS: <a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2023\/10\/IP2023_PPS_EasternUganda.pdf\" target=\"_blank\" rel=\"noopener\">Oportunidad de aprendizaje internacional. Resultados de una encuesta de prevalencia de puntos de prescripci\u00f3n en Uganda oriental.<\/a><\/p><p><strong>ECCMID Copenhague 2023<\/strong><\/p><p><a href=\"https:\/\/www.eccmid.org\/\" target=\"_blank\" rel=\"noopener\">Visite el sitio web<\/a><\/p><p>Descargue los carteles de Global-PPS:<\/p><ul><li aria-level=\"1\"><b>Global-PPS<\/b>:\u00a0<a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2023\/04\/ECCMID2023_P2050_antimycotics_antifungals-.pdf\" target=\"_blank\" rel=\"noopener\">Patrones de prescripci\u00f3n de antimic\u00f3ticos y antif\u00fangicos en todo el mundo: resultados de la Encuesta mundial de prevalencia puntual sobre consumo y resistencia a los antimicrobianos.<\/a>\u00a0<\/li><li aria-level=\"1\"><b>Filipinas\u00a0<\/b>(2 carteles):<ul><li aria-level=\"2\"><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2023\/04\/ECCMID2023_P2299_Philippines.pdf\" target=\"_blank\" rel=\"noopener\">Uso de antimicrobianos para la neumon\u00eda asociada a la atenci\u00f3n sanitaria en Filipinas de 2017 a 2021: resultados de la encuesta de prevalencia puntual global (Global-PPS)<\/a>\u00a0<\/li><li aria-level=\"2\"><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2023\/04\/ECCMID2023_P2309_Philippines.pdf\" target=\"_blank\" rel=\"noopener\">Resultados de la encuesta de prevalencia puntual del uso de antimicrobianos en hospitales privados y p\u00fablicos de Filipinas de 2019 a 2021\u00a0<\/a><\/li><\/ul><\/li><li aria-level=\"1\"><b>Guatemala<\/b>:\u00a0<a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2023\/04\/ECCMID2023_poster_2351_Guatemala.pdf\" target=\"_blank\" rel=\"noopener\">La encuesta mundial de prevalencia puntual del consumo y la resistencia a los antimicrobianos (Global-PPS): resultados de la prescripci\u00f3n de antimicrobianos en 4 hospitales guatemaltecos en 2021<\/a>\u00a0<\/li><li aria-level=\"1\"><b>Zambia<\/b>:\u00a0<a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2023\/04\/ECCMID2023_P2366_David-Banda-Zambia31-03-23.pdf\" target=\"_blank\" rel=\"noopener\">Medici\u00f3n del uso de antimicrobianos en Zambia: resultados del Global-PPS en seis centros sanitarios<\/a>\u00a0<\/li><li aria-level=\"1\"><b>Kenia y Tanzania<\/b>:\u00a0<a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2023\/04\/ECCMID2023_PJK0908_Kenya.pdf\" target=\"_blank\" rel=\"noopener\">Resultados de la encuesta mundial de prevalencia puntual del consumo y la resistencia a los antimicrobianos (Global-PPS) en hospitales p\u00fablicos y privados de Kenia y Tanzania en 2021.<\/a>\u00a0<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7465\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-7465\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Congresos 2022<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7465\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-7465\"><p><strong>ECCMID Lisboa 2022<\/strong><\/p><p><a href=\"https:\/\/www.eccmid.org\/\" target=\"_blank\" rel=\"noopener\">Visite el sitio web<\/a><\/p><p>Descargue los carteles de Global-PPS:<\/p><ul><li><a href=\"https:\/\/www.global-pps.com\/es\/eccmid-2022_onsite-poster-covid_final\/\" target=\"_blank\" rel=\"noopener\">Encuesta mundial de prevalencia puntual del consumo y la resistencia a los antimicrobianos (Global-PPS): 2021 resultados de la prescripci\u00f3n de antimicrobianos para pacientes COVID-19 en Filipinas<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/es\/eccmid-2022_onsite-poster-sp_final\/\" target=\"_blank\" rel=\"noopener\">Prescripci\u00f3n de antibi\u00f3ticos para profilaxis quir\u00fargica en 15 hospitales filipinos: resultados de un periodo de vigilancia de 4 a\u00f1os mediante encuestas de prevalencia puntual repetidas<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/es\/eccmid-2022_onsite-poster-forgottenabs_final\/\" target=\"_blank\" rel=\"noopener\">Evaluaci\u00f3n de la disponibilidad de antibi\u00f3ticos olvidados mediante la Encuesta Mundial de Prevalencia Puntual del Consumo y la Resistencia a los Antimicrobianos (Global-PPS)<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/es\/eccmid-2022_onsite-poster_montenegro\/\" target=\"_blank\" rel=\"noopener\">Resultados de la Encuesta mundial de prevalencia puntual del consumo de antimicrobianos y la resistencia a los mismos (Global-PPS) sobre la prescripci\u00f3n de antimicrobianos en Montenegro en 2021<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/es\/eccmid-2022_onsite-poster_geo_final\/\" target=\"_blank\" rel=\"noopener\">Encuesta mundial de prevalencia puntual del uso de antibi\u00f3ticos en pacientes hospitalizados por COVID-19 en Georgia. \u00bfQu\u00e9 ha cambiado con la pandemia?<\/a><\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7466\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-7466\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Congresos 2021<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7466\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-7466\"><p><strong>15\u00ba Congreso Internacional de Microbiolog\u00eda Cl\u00ednica Profesor Alborzi, Shiraz, Ir\u00e1n - 2021<\/strong><\/p><p>Visite el sitio web:\u00a0<a href=\"https:\/\/congressapp.ir\/paiccm2021\/index.php\" target=\"_blank\" rel=\"noopener\">https:\/\/congressapp.ir\/paiccm2021\/index.php<\/a>\u00a0 \u00a0<\/p><p><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/11\/Global-PPS_congress-Iran-Sepsis-22-10-2021.pdf\" target=\"_blank\" rel=\"noopener\">Descargar la presentaci\u00f3n de Global-PPS<\/a>: Carga y gesti\u00f3n global actual de la sepsis en el mundo - Lecciones del Global-PPS\u00a0<\/p><p><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/11\/AMS-presentation_final_5102021.pdf\" target=\"_blank\" rel=\"noopener\">Descargar la presentaci\u00f3n de Global-PPS<\/a>: El Global-PPS - De la recogida de datos a las acciones de la MGA\u00a0<\/p><p><strong>31\u00ba ECCMID 2021 en l\u00ednea<\/strong><\/p><p>Visite el sitio web\u00a0<a href=\"https:\/\/www.eccmid.org\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.eccmid.org\/<\/a><\/p><p>Descargue las presentaciones de Global-PPS:<\/p><ul><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/07\/1-Worldwide-prescribing-of-SAP_Ines-Pauwels_ECCMID-2021.pdf\" target=\"_blank\" rel=\"noopener\"><strong>En todo el mundo<\/strong>prescripci\u00f3n de profilaxis antibi\u00f3tica quir\u00fargica: resultados del Global-PPS 2015-2020<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/07\/2-Longitudinal-Belgian-Global-PPS-and-QI_Ann-Versporten_ECCMID-2021.pdf\" target=\"_blank\" rel=\"noopener\">Seguimiento de los indicadores de calidad del uso de antibi\u00f3ticos en\u00a0<strong>Belga\u00a0<\/strong>hospitales<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/07\/3-Global-PPS-as-a-tool-to-support-AMS-in-the-Philippines_Mari-Rose-De-Los-Reyes_ECCMID-2021.pdf\" target=\"_blank\" rel=\"noopener\">El Global-PPS como herramienta de apoyo a la gesti\u00f3n antimicrobiana: Resultados longitudinales en 10 hospitales de la\u00a0<strong>Filipinas<\/strong><\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/07\/4-Longitudinal-Global-PPS-in-Nigeria.-Progress-challenges-and-opportunities_Oyin-Oduyebo_ECCMID-2021.pdf\" target=\"_blank\" rel=\"noopener\">Global-PPS longitudinal en\u00a0<strong>Nigeria<\/strong>Avances, retos y perspectivas<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/07\/5-poster_SP-in-NG_Kenneth-Iregbu_ECCMID-2021.pdf\" target=\"_blank\" rel=\"noopener\">Pauta de profilaxis antibi\u00f3tica quir\u00fargica en 18\u00a0<strong>Nigeria<\/strong>hospitales<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/07\/6-Poster-Global-PPS-in-Iran_Jafar-Soltani_ECCMID-2021.pdf\" target=\"_blank\" rel=\"noopener\">Repetici\u00f3n de Global-PPS en los hospitales de Sanandaj,\u00a0<strong>Ir\u00e1n<\/strong>una implicaci\u00f3n para la administraci\u00f3n de antibi\u00f3ticos<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/07\/7-poster_Global-PPS-in-Cote-dIvoire_Adele-Kacou-NDouba_ECCMID-2021.pdf\" target=\"_blank\" rel=\"noopener\">El Global-PPS en\u00a0<strong>Costa de Marfil<\/strong><\/a><\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7467\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-7467\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Congresos 2020<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7467\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-7467\"><p><strong>Conferencia de la Sociedad de Microbiolog\u00eda Cl\u00ednica y Enfermedades Infecciosas de Nigeria (CLIMIDSON) 26-27 de noviembre de 2020<\/strong><\/p><p><a href=\"https:\/\/www.global-pps.com\/es\/2020-climidson-conference-in-nigeria\/\" target=\"_blank\" rel=\"noopener\">M\u00e1s informaci\u00f3n<\/a><\/p><p><a href=\"https:\/\/www.global-pps.com\/es\/climidson-report-modified_\/\" target=\"_blank\" rel=\"noopener\">Leer un informe resumido<\/a><\/p><p><a href=\"https:\/\/www.global-pps.com\/es\/global-pps_2020_congress_climidson_nigeria-4\/\" target=\"_blank\" rel=\"noopener\">Descargar la presentaci\u00f3n de Global-PPS<\/a><\/p><p><a href=\"https:\/\/climidson.org\/\" target=\"_blank\" rel=\"noopener\">Visite el sitio web<\/a><\/p><p><strong>3er Congreso Internacional de Enfermer\u00eda sobre Estrategias de Prevenci\u00f3n de las IRAS, Mashhad, Ir\u00e1n - 2020<\/strong><\/p><p><a href=\"https:\/\/cong-phcai.mums.ac.ir\/incps\/\" target=\"_blank\" rel=\"noopener\">Visite el sitio web<\/a><\/p><p><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/Global-PPS_INCPS_congress_Mashhad_Iran_17-11-20.pdf\" target=\"_blank\" rel=\"noopener\">Descargar la presentaci\u00f3n de Global-PPS<\/a>: \u201cGlobal-PPS y el papel de la enfermera en la capacitaci\u00f3n para la administraci\u00f3n antimicrobiana<strong>\u201d<\/strong><\/p><p><a href=\"https:\/\/psj.mums.ac.ir\/issue_1788_1972.html\" target=\"_blank\" rel=\"noopener\">Descargar los res\u00famenes:<\/a>\u00a0publicado en el\u00a0<em>Patient Safety and Quality Improvement Journal; Volumen 8, Suplemento 1\u00a0<\/em><\/p><p><strong>ASM Microbio 2020<\/strong><\/p><p><a href=\"https:\/\/asm.org\/Events\/ASM-Microbe\/Home\" target=\"_blank\" rel=\"noopener\">Visite el sitio web<\/a><\/p><p><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/PPS-of-antimicrobial-use-in-5-secondary-hospitals-in-west-side-Saitama-prefecture-in-Japan.pdf\" target=\"_blank\" rel=\"noopener\">Descargar el cartel de la ASM 2020<\/a>: PPS del uso de antimicrobianos en 5 hospitales secundarios de la prefectura occidental de Saitama, Jap\u00f3n. Centrado en la terapia de la neumon\u00eda.<\/p><p><a href=\"https:\/\/virtualmeeting.ctimeetingtech.com\/asm2020\/attendee\/eposter\/poster\/898?q=Saitama&amp;fbclid=IwAR0YlRNJdrM0qNCxfnhgVh4n3_SCIT2-eOi8f69y2jSyRZvJxIG_Z3RZMp4\" target=\"_blank\" rel=\"noopener\">Escuchar la presentaci\u00f3n<\/a><\/p><p><strong>14\u00ba Congreso Internacional de Microbiolog\u00eda Cl\u00ednica Profesor Alborzi, Mashhad, Ir\u00e1n - 2020<\/strong><\/p><p><a href=\"https:\/\/cong-phcai.mums.ac.ir\/phcai\/index.php\" target=\"_blank\" rel=\"noopener\">Visite el sitio web<\/a><\/p><p><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/Global-PPS_PHCAI_congress_Mashhad_Iran_12-11-20.pdf\" target=\"_blank\" rel=\"noopener\">Descargar la presentaci\u00f3n de Global-PPS<\/a>: \u201cGlobal-PPS y desarrollo de capacidades para la administraci\u00f3n de antimicrobianos - Ampliaci\u00f3n con el m\u00f3dulo HAI que permite la vigilancia de pacientes COVID-19\u201d<\/p><p><a href=\"https:\/\/psj.mums.ac.ir\/issue_1788_1972.html\" target=\"_blank\" rel=\"noopener\">Descargar los res\u00famenes<\/a>\u00a0publicado en el\u00a0<em>Patient Safety and Quality Improvement Journal; Volumen 8, Suplemento 1<\/em><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7468\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-7468\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Congresos 2019<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7468\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-7468\"><p><strong>Simposio internacional sobre cuidados intensivos y medicina de urgencias - ESICEM Bruselas 2019<\/strong><\/p><p><a href=\"https:\/\/www.isicem.org\/\" target=\"_blank\" rel=\"noopener\">Visite el sitio web<\/a><\/p><p><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/07\/ISICEM_Global-PPS_ICU.pdf\" target=\"_blank\" rel=\"noopener\">Descargar las presentaciones de Global-PPS<\/a><\/p><p><strong>ECCMID \u00c1msterdam 2019<\/strong><\/p><p><a href=\"https:\/\/www.eccmid.org\/\" target=\"_blank\" rel=\"noopener\">Visite el sitio web<\/a><\/p><p>Descargue las presentaciones de Global-PPS:<\/p><ul><li><a href=\"https:\/\/www.global-pps.com\/es\/eccmid_2019_paediatric-prophylactic-use\/\" target=\"_blank\" rel=\"noopener\">Elevada proporci\u00f3n de uso de antibi\u00f3ticos profil\u00e1cticos pedi\u00e1tricos: an\u00e1lisis a partir de datos de encuestas de prevalencia puntual de 56 pa\u00edses<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/es\/eccmid_2019_socioeconomic-and-environmental-factors-for-mdr-gramnegatives\/\" target=\"_blank\" rel=\"noopener\">The Global-PPS: Los factores socioecon\u00f3micos y ambientales pueden contribuir m\u00e1s a la multirresistencia en infecciones bacterianas por gramnegativos que la prevalencia de antibi\u00f3ticos en entornos hospitalarios.<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/es\/eccmid_2019_quality-indicators-egypt\/\" target=\"_blank\" rel=\"noopener\">Encuesta mundial de prevalencia puntual del consumo y la resistencia a los antimicrobianos (Global-PPS): Indicadores de calidad de la prescripci\u00f3n de antimicrobianos en los hospitales egipcios<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/es\/eccmid_2019_results-of-antimicrobial-prescribing-in-mexico\/\" target=\"_blank\" rel=\"noopener\">La Encuesta Global de Prevalencia Puntual de Consumo y Resistencia a los Antimicrobianos (Global-PPS): Primeros resultados de la prescripci\u00f3n de antimicrobianos en 5 hospitales mexicanos<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/es\/eccmid_2019_global-pps-and-ecdc_belgium_2017\/\" target=\"_blank\" rel=\"noopener\">Resultados de las encuestas de prevalencia puntual mundial y del ECDC sobre el uso de antimicrobianos y las infecciones asociadas a la atenci\u00f3n sanitaria en los hospitales belgas de cuidados agudos en 2017<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/es\/eccmid_2019_global-pps-and-ecdc-uti-belgium\/\" target=\"_blank\" rel=\"noopener\">Encuesta mundial y del CEPCE sobre prevalencia puntual del uso de antimicrobianos y las infecciones relacionadas con la asistencia sanitaria: Prescripci\u00f3n de antimicrobianos y resultados de las infecciones urinarias en B\u00e9lgica<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/es\/eccmid_2019_results-of-antimicrobial-prescribing-in-india\/\" target=\"_blank\" rel=\"noopener\">Encuesta mundial de prevalencia puntual del consumo y la resistencia a los antimicrobianos (Global-PPS): Resultados de la prescripci\u00f3n de antimicrobianos en la India<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/es\/eccmid_2019_antifungals-brazil\/\" target=\"_blank\" rel=\"noopener\">Patr\u00f3n de Prescripci\u00f3n de Antif\u00fangicos en 18 Hospitales Brasile\u00f1os: una Encuesta de Prevalencia Puntual<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-admin\/post.php?post=14300&amp;action=edit\" target=\"_blank\" rel=\"noopener\">Utilizaci\u00f3n de los datos de la Encuesta de Prevalencia Puntual de Antibi\u00f3ticos para estimar la prevalencia de las infecciones relacionadas con la asistencia sanitaria en ni\u00f1os: an\u00e1lisis de 27 pa\u00edses<\/a><\/li><\/ul><p>Entrevistas de la reuni\u00f3n de participantes clave de Global-PPS previa a la ECCMID:<\/p><p><a href=\"https:\/\/www.youtube.com\/watch?v=xwHIFk79Wf0\" target=\"_blank\" rel=\"noopener\">Jorgen Stassijns, MSF, 2019<\/a><br \/><a href=\"https:\/\/www.youtube.com\/watch?v=YvN8oM2oZ04\">Prof. Goossens, UA, 2019<\/a><br \/><a href=\"https:\/\/www.youtube.com\/watch?v=lnBEFD_Gl5w\" target=\"_blank\" rel=\"noopener\">Daouda Sissoko, bioM\u00e9rieux \u00c1frica, 2019<\/a><\/p><p><a href=\"https:\/\/www.youtube.com\/watch?v=k9zvw3oUnUw&amp;list=PL5PzuNWUbdRRrLwTtKvdgFO_vUP9YAxDY&amp;index=5\" target=\"_blank\" rel=\"noopener\">Canad\u00e1<\/a><\/p><p>M\u00e9xico<\/p><ul><li><a href=\"https:\/\/www.youtube.com\/watch?v=2eSC302roAM&amp;list=PL5PzuNWUbdRRrLwTtKvdgFO_vUP9YAxDY&amp;index=8\" target=\"_blank\" rel=\"noopener\">V\u00eddeo 1<\/a><\/li><li><a href=\"https:\/\/www.youtube.com\/watch?v=ea9UUO74bBM&amp;list=PL5PzuNWUbdRRrLwTtKvdgFO_vUP9YAxDY&amp;index=9\" target=\"_blank\" rel=\"noopener\">V\u00eddeo 2<\/a><\/li><\/ul><p><strong>ICPIC 2019 (Conferencia internacional sobre prevenci\u00f3n y control de infecciones), Ginebra, Suiza.<\/strong><\/p><p><a href=\"https:\/\/www.conference.icpic.com\/\" target=\"_blank\" rel=\"noopener\">Visite el sitio web<\/a><\/p><p><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/ICPIC_2019_abstract-book.pdf\" target=\"_blank\" rel=\"noopener\">Descargar el libro de res\u00famenes de la ICPIC 2019<\/a><\/p><p><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/Oral-presentation-on-Healthcare-Associated-Infections_results-of-the-2017-and-2018-Global-PPS.pdf\" target=\"_blank\" rel=\"noopener\">Descargue la presentaci\u00f3n oral sobre Infecciones asociadas a la asistencia sanitaria - Resultados del Global-PPS de 2017 y 2018<\/a><\/p><p>Descargue las presentaciones de Global-PPS:<\/p><ul><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/Quantity-and-quality-of-antibiotic-prescribing-for-sepsis-in-hospitalised-adults-results-of-the-2015-2017-and-2018-Global-PPS.pdf\" target=\"_blank\" rel=\"noopener\">Cantidad y calidad de la prescripci\u00f3n de antibi\u00f3ticos para la sepsis en adultos hospitalizados: resultados de los Global-PPS de 2015, 2017 y 2018<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/Assessing-the-learning-needs-and-barriers-for-implementation-of-AMS-in-hospitals-that-have-particpated-in-the-Global-PPS.pdf\" target=\"_blank\" rel=\"noopener\">Evaluar las necesidades de aprendizaje y los obst\u00e1culos para la aplicaci\u00f3n de la administraci\u00f3n de antimicrobianos en los hospitales que han participado en el Global PPS.<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/Antimicrobial-prescribing-pattern-in-HAIs-in-27-Brazilian-hospitals_2017-and-2018-point-prevalence-surveys.pdf\" target=\"_blank\" rel=\"noopener\">Patrones de prescripci\u00f3n de antimicrobianos en infecciones asociadas a la atenci\u00f3n sanitaria en 27 hospitales brasile\u00f1os: encuestas de prevalencia puntual de 2017 y 2018<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/The-Global-PPS_results-of-antimicrobial-prescribing-in-Burkina-Faso.pdf\" target=\"_blank\" rel=\"noopener\">Global-PPS: resultados de la prescripci\u00f3n de antimicrobianos en Burkina Faso<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/The-Global-PPS_2015-2017-and-2018-results-of-antimicrobial-prescribing-for-pneumonia-in-Georgia-1.pdf\" target=\"_blank\" rel=\"noopener\">El Global-PPS: resultados de 2015 , 2017 y 2018 de la prescripci\u00f3n de antimicrobianos para la neumon\u00eda en Georgia.<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/The-Global-PPS_results-of-antimicrobial-prescribing-for-a-general-hospital-in-Urmia-Iran.pdf\" target=\"_blank\" rel=\"noopener\">Global-PPS: resultados de la prescripci\u00f3n de antimicrobianos en un hospital general de Urmia (Ir\u00e1n)<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/The-Global-PPS_2018-2019-results-for-hospital-acquired-pneumonia-in-8-Mexican-hospitals.pdf\" target=\"_blank\" rel=\"noopener\">El Global-PPS: resultados 2018-2019 para neumon\u00eda adquirida en el hospital en 8 hospitales mexicanos<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/The-Global-PPS_results-of-antimicrobial-prescribing-in-Togo.pdf\" target=\"_blank\" rel=\"noopener\">Global-PPS: resultados de la prescripci\u00f3n de antimicrobianos en Togo<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/The-Global-PPS_2018-results-of-antimicrobial-prescribing-for-healthcare-associated-infections-in-Tunisia.pdf\" target=\"_blank\" rel=\"noopener\">El Global-PPS: resultados de 2018 de la prescripci\u00f3n de antimicrobianos para infecciones asociadas a la atenci\u00f3n sanitaria en T\u00fanez<\/a><\/li><\/ul><p><strong>Semana de la identificaci\u00f3n 2019 - Washington DC<\/strong><\/p><p><a href=\"https:\/\/viivhealthcare.com\/en-gb\/idweek-2019\/\" target=\"_blank\" rel=\"noopener\">Visite el sitio web<\/a><\/p><p><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/Poster-Global-PPS-Canadian-Peds-Results-IDWeek-2019.pdf\" target=\"_blank\" rel=\"noopener\">Descargar el cartel de Global-PPS<\/a>: Resultados pedi\u00e1tricos de 26 hospitales canadienses<\/p><p><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/IDWeek-poster_Global-PPS_Philippines.pdf\" target=\"_blank\" rel=\"noopener\">Descargar el cartel de Global-PPS<\/a>: Cantidad y calidad de la prescripci\u00f3n de antimicrobianos para pacientes hospitalizados con neumon\u00eda en Filipinas en 2018<\/p><p><strong>XVI-HISICON 2019, Calcuta, India<\/strong><\/p><p><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/HISICON-E-Poster-S-Sengupta_-1.pdf\" target=\"_blank\" rel=\"noopener\">Descargar el cartel<\/a>: \u201c Estudio de indicadores de calidad en profilaxis quir\u00fargica entre 5 pa\u00edses asi\u00e1ticos a trav\u00e9s de Global PPS<\/p><p><strong>WSPID 2019 - Manila, Filipinas<\/strong><\/p><p><a href=\"https:\/\/wspid2019.kenes.com\/\" target=\"_blank\" rel=\"noopener\">Visite el sitio web<\/a><\/p><p><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/WSPID-Global-PPS-slides-Oct-2019-1.pdf\" target=\"_blank\" rel=\"noopener\">Descargar la presentaci\u00f3n<\/a>: Global-PPS 2015, 2017, 2018 : Resultados de la prescripci\u00f3n mundial de antimicrobianos para la neumon\u00eda pedi\u00e1trica adquirida en la comunidad y asociada a la atenci\u00f3n sanitaria\u201d.\u201d<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7469\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-7469\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Congresos 2018<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7469\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-7469\"><p><strong>ASLM (Sociedad Africana de Medicina de Laboratorio) 2018 - Prevenir y controlar la pr\u00f3xima pandemia: El papel del laboratorio, Abuja, Nigeria.<\/strong><\/p><p><a href=\"https:\/\/aslm2018.org\/\" target=\"_blank\" rel=\"noopener\">Visite el sitio web<\/a><\/p><p><a href=\"https:\/\/www.global-pps.com\/es\/aslm_2018_global-pps-in-kenia\/\" target=\"_blank\" rel=\"noopener\">Global-PPS en Kenia<\/a><br \/><a href=\"https:\/\/www.global-pps.com\/wp-admin\/post.php?post=14291&amp;action=edit\" target=\"_blank\" rel=\"noopener\">Global-PPS en T\u00fanez<\/a><br \/><a href=\"https:\/\/www.global-pps.com\/es\/aslm_2018_global-pps-in-nigeria\/\" target=\"_blank\" rel=\"noopener\">Global-PPS en Nigeria<\/a><\/p><p><strong>Resistencia a los antibi\u00f3ticos: De la investigaci\u00f3n a la acci\u00f3n, 59\u00ba Coloquio del IMT, 5-7 de diciembre de 2018, Phnom Penh, Camboya.<\/strong><\/p><p><a href=\"https:\/\/www.antibiotic-resistance-2018.org\/\" target=\"_blank\" rel=\"noopener\">Visite el sitio web<\/a><\/p><p><a href=\"https:\/\/www.global-pps.com\/wp-admin\/post.php?post=14285&amp;action=edit\" target=\"_blank\" rel=\"noopener\">Presentaci\u00f3n del Global-PPS en el Hospital Infantil de Angkor<\/a><\/p><p><a href=\"https:\/\/www.global-pps.com\/es\/phnompenh_2018_results-of-antimicrobial-prescribing-in-india\/\" target=\"_blank\" rel=\"noopener\">Presentaci\u00f3n del Global-PPS: Resultados de la prescripci\u00f3n de antimicrobianos en la India<\/a><\/p><p><a href=\"https:\/\/www.global-pps.com\/es\/phnompenh_2018_antimicrobial-prescribing-pneumonia-philippines\/\" target=\"_blank\" rel=\"noopener\">Presentaci\u00f3n sobre la prescripci\u00f3n de antibi\u00f3ticos para adultos y ni\u00f1os con neumon\u00eda en Filipinas<\/a><\/p><p><strong>Journ\u00e9e Infections Nosocomiales, 10\u00e8me \u00e9dition, 20 de noviembre de 2018, Lyon, Francia.<\/strong><\/p><p><a href=\"https:\/\/www.global-pps.com\/es\/lyon_2018_antimicrobial-consumption-and-hai\/\" target=\"_blank\" rel=\"noopener\">Encuesta mundial de prevalencia puntual: Consumo de antimicrobianos e infecciones relacionadas con la asistencia sanitaria<\/a><\/p><p><strong>2\u00ba Llamamiento a la acci\u00f3n sobre la resistencia a los antimicrobianos, 19-20 de noviembre de 2018, Accra, Ghana.<\/strong><\/p><p><a href=\"https:\/\/wellcome.org\/news\/second-global-call-action-against-drug-resistant-infections\" target=\"_blank\" rel=\"noopener\">Visite el sitio web<\/a><\/p><p><a href=\"https:\/\/www.global-pps.com\/es\/accra_2018_global-pps_loop\/\" target=\"_blank\" rel=\"noopener\">Almuerzo Presentaci\u00f3n del bucle Global-PPS<\/a><\/p><p><a href=\"https:\/\/www.global-pps.com\/es\/accra_2018_pioneers_presentation\/\" target=\"_blank\" rel=\"noopener\">Sesi\u00f3n pionera Presentaci\u00f3n de Global-PPS<\/a><\/p><p><strong>7\u00ba congreso de la ICAN, Ciudad del Cabo, Sud\u00e1frica 2018<\/strong><\/p><p><a href=\"http:\/\/www.icanetwork.co.za\/conferences\/ican-congress-2018\/\" target=\"_blank\" rel=\"noopener\">Visite el sitio web<\/a><\/p><p><a href=\"https:\/\/www.global-pps.com\/es\/ican_2018_state-of-the-art-lecture\/\" target=\"_blank\" rel=\"noopener\">Conferencia sobre Global-PPS<\/a><\/p><p><a href=\"https:\/\/www.global-pps.com\/es\/ican_2018_prophylactic-antimicrobial-use-egypt\/\" target=\"_blank\" rel=\"noopener\">Uso profil\u00e1ctico de antimicrobianos en procedimientos quir\u00fargicos en Egipto<\/a><\/p><p><a href=\"https:\/\/www.global-pps.com\/es\/ican_2018_antimicrobial-quality-indicators\/\" target=\"_blank\" rel=\"noopener\">Global-PPS e indicadores de calidad antimicrobiana<\/a><\/p><p><a href=\"https:\/\/www.global-pps.com\/es\/ican_2018_egyptian-experience-using-global-pps-tools\/\" target=\"_blank\" rel=\"noopener\">Experiencia egipcia en el uso de herramientas Global-PPS<\/a><\/p><p><a href=\"https:\/\/www.global-pps.com\/es\/ican_2018_poor-laboratory-use-in-nigerian-hospitals\/\" target=\"_blank\" rel=\"noopener\">El uso deficiente de los laboratorios como obst\u00e1culo para la administraci\u00f3n de antimicrobianos en los hospitales nigerianos<\/a><\/p><p><a href=\"https:\/\/www.global-pps.com\/es\/ican_2018_results-of-antimicrobial-prescribing-guinea\/\" target=\"_blank\" rel=\"noopener\">Global-PPS: resultados de la prescripci\u00f3n de antimicrobianos en Guinea en 2017.<\/a><\/p><p><a href=\"https:\/\/www.global-pps.com\/wp-admin\/post.php?post=14277&amp;action=edit\" target=\"_blank\" rel=\"noopener\">Presentaci\u00f3n del m\u00e9todo Global-PPS en el taller posterior al congreso<\/a><\/p><p><strong>XIX Congreso de Calidad Asistencial del Principado de Asturias, Espa\u00f1a 2018<\/strong><\/p><p><a href=\"https:\/\/pasqal.org\/\">Visite el sitio web<\/a><br \/><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/PASQAL-2018-01M2USO.pdf\" target=\"_blank\" rel=\"noopener\">Descargar la presentaci\u00f3n oral de Global-PPS<\/a>\u00a0sobre el uso de antibi\u00f3ticos en un hospital de Asturias, Espa\u00f1a<\/p><p><strong>Congreso SEIMC (Sociedad Espa\u00f1ola de Enfermedades Infecciosas y Microbiolog\u00eda Cl\u00ednica), Bilbao, Espa\u00f1a, 2018.<\/strong><\/p><p><a href=\"https:\/\/www.seimc.org\/\" target=\"_blank\" rel=\"noopener\">Visite el sitio web<\/a><br \/><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/Poster-SEIMC-2018.pdf\" target=\"_blank\" rel=\"noopener\">Descargar el cartel de Global-PPS<\/a>\u00a0sobre el uso de antibi\u00f3ticos en los hospitales de Andaluc\u00eda, Espa\u00f1a<br \/><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/07\/Presentacio%CC%81n-Global-PPS-SEIMC-2018.pdf\" target=\"_blank\" rel=\"noopener\">Descargar la presentaci\u00f3n oral de Global-PPS<\/a>\u00a0sobre el uso emp\u00edrico de antibi\u00f3ticos en hospitales de Andaluc\u00eda, Espa\u00f1a<\/p><p><strong>ECCMID Madrid 2018<\/strong><\/p><p><a href=\"http:\/\/www.eccmid.org\/\" target=\"_blank\" rel=\"noopener\">Visite el sitio web del ECCMID<\/a><br \/><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/Overview-accepted-abstracts-ECCMID-2018-website.pdf\" target=\"_blank\" rel=\"noopener\">Descargar los carteles del ECCMID<\/a><br \/><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/BRCH-Global-PPS-180406-web-Xs.pdf\" target=\"_blank\" rel=\"noopener\">Descargar el folleto de la ECCMID 2018<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-74610\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-74610\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Congresos 2017<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-74610\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-74610\"><p><strong>29\u00ba congreso internacional de pediatr\u00eda, 26-29 de octubre de 2017, Teher\u00e1n, Ir\u00e1n.<\/strong><\/p><p><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/A-PPS-of-Antibiotic-Prescriptions3-Sanandaj-Hospitals-Dr-Soltani.pdf\" target=\"_blank\" rel=\"noopener\">Descargar la presentaci\u00f3n sobre Un PPS de prescripciones de antibi\u00f3ticos<\/a><\/p><p><strong>11\u00ba Congreso Internacional de Microbiolog\u00eda Cl\u00ednica Profesor Alborzi, 21-23 de noviembre de 2017, Shiraz, Ir\u00e1n.<\/strong><\/p><p><a href=\"http:\/\/alborzi-iccm2017.sums.ac.ir\/en\/\" target=\"_blank\" rel=\"noopener\">Visite el sitio web<\/a><\/p><p><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/A-Longitudinal-Study-of-PPS-Dr-Soltani-.pdf\" target=\"_blank\" rel=\"noopener\">Descargar el estudio longitudinal de PPS del Dr. Soltani<\/a><\/p><p><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/Antibiotic-Resistances-Profile3-in-Iran-Dr-Soltani.pdf\" target=\"_blank\" rel=\"noopener\">Descargar la presentaci\u00f3n sobre perfiles de resistencia a los antibi\u00f3ticos<\/a><\/p><p><strong>10\u00ba Congreso Europeo de Medicina Tropical y Salud Internacional, Amberes, B\u00e9lgica, 2017.<\/strong><\/p><p><a href=\"http:\/\/www.ectmih2017.be\/\" target=\"_blank\" rel=\"noopener\">Visite el sitio web<\/a><br \/>Descargue los carteles de la ECTMIH 2017:<\/p><ul><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/ECTMIH-2017-5p78-Costa-Rica.pdf\" target=\"_blank\" rel=\"noopener\">ECTMIH-2017 - Costa Rica<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/ECTMIH-2017-3P30-Guinea.pdf\" target=\"_blank\" rel=\"noopener\">ECTMIH-2017 - Guinea<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/ECTMIH-2017-5P95-Ghana.pdf\" target=\"_blank\" rel=\"noopener\">ECTMIH-2017 - Ghana<\/a><\/li><\/ul><p><strong>Congreso ECCMID, Viena 2017<\/strong><\/p><p><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/ECCMID2017_Global-PPS_Cancer-Patients_Final.pdf\" target=\"_blank\" rel=\"noopener\">Caracter\u00edsticas de la prescripci\u00f3n de antimicrobianos en pacientes con c\u00e1ncer<\/a><br \/><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2017\/04\/ECCMID_2017-sepsis_Global-PPS_poster_to-be-presented_24April_P1164.pdf\" target=\"_blank\" rel=\"noopener\">Utilidad de los datos de las encuestas en la evaluaci\u00f3n y el tratamiento de la sepsis<\/a><\/p><p><strong>La conferencia de primavera 2017 de la BSAC : El desaf\u00edo global de las infecciones bacterianas gramnegativas multirresistentes.<\/strong><\/p><p><a href=\"http:\/\/bsac-conference.com\/\" target=\"_blank\" rel=\"noopener\">Visite el sitio web de BSAC<\/a><br \/><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/Global-PPS_BSAC-London_14march2017-final.pdf\" target=\"_blank\" rel=\"noopener\">Descargue la presentaci\u00f3n:<\/a>\u201cCarga y gesti\u00f3n global actual de las infecciones por GNB: Lecciones del Global-PPS de consumo de antimicrobianos y resistencia en 335 hospitales de todo el mundo\u201d<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-74611\" class=\"elementor-tab-title\" data-tab=\"11\" role=\"button\" aria-controls=\"elementor-tab-content-74611\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Congresos 2016<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-74611\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"11\" role=\"region\" aria-labelledby=\"elementor-tab-title-74611\"><p><strong>Simposio de la Red Internacional del Instituto Pasteur 2016, Par\u00eds, Francia.<\/strong><\/p><p><a href=\"https:\/\/www.pasteur.fr\/en\/institut-pasteur\/institut-pasteur-world\/news\/3rd-institut-pasteur-international-network-symposium-celebrates-biomarkers\/\" target=\"_blank\" rel=\"noopener\">Visite el sitio web<\/a><br \/><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/IP-Network-poster-GPPS_22-Nov-2016.pdf\" target=\"_blank\" rel=\"noopener\">Descargue el p\u00f3ster con los resultados sobre experiencias en pa\u00edses de renta baja y media; y sobre el uso de biomarcadores de infecci\u00f3n.<\/a><\/p><p><strong>Reuni\u00f3n sobre enfermedades infecciosas pedi\u00e1tricas - ESPID 2016<\/strong><\/p><p><a href=\"http:\/\/espid2016.kenes.com\/\" target=\"_blank\" rel=\"noopener\">Visite el sitio web de ESPID<\/a><br \/><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/ESPID-G-PPS-3may16.pdf\" target=\"_blank\" rel=\"noopener\">Descargue el p\u00f3ster Global-PPS sobre los resultados pedi\u00e1tricos mundiales<\/a><\/p><p><strong>Congreso del Golfo de Microbiolog\u00eda Cl\u00ednica y Enfermedades Infecciosas, mayo de 2016, Dubai, EAU.<\/strong><\/p><p><a href=\"https:\/\/www.clocate.com\/conference\/gulf-congress-of-clinical-microbiology-and-infectious-diseases-gccmid\/67918\/\" target=\"_blank\" rel=\"noopener\">Visite el sitio web<\/a><br \/><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/GCC-Poster-MushiraEnani-Final.pdf\" target=\"_blank\" rel=\"noopener\">Descargue el cartel:\u00a0<\/a>La Dra. Mushira Enani, de la Ciudad M\u00e9dica Rey Fahad, Riad, Reino de Arabia Saud\u00ed, gan\u00f3 el 1er premio con su p\u00f3ster global-PPS presentado durante el 1er Congreso del Golfo de Microbiolog\u00eda Cl\u00ednica y Enfermedades Infecciosas, celebrado del 4 al 7 de mayo de 2016 en Dub\u00e1i, EAU.<\/p><p><strong>X Congreso Internacional de Microbiolog\u00eda Cl\u00ednica en Sanandaj, Kurdist\u00e1n, Ir\u00e1n 2016.<\/strong><\/p><p><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/Global-PPS_Sanandaj_-28sept2016_results.pdf\" target=\"_blank\" rel=\"noopener\">Presentaci\u00f3n de los resultados globales, as\u00ed como de los resultados iran\u00edes (dos hospitales de tercer nivel) y del este y sur de Asia.<\/a><\/p><p><strong>Conferencia AMMI Canad\u00e1 2016<\/strong><\/p><p><a href=\"https:\/\/www.ammi.ca\/\" target=\"_blank\" rel=\"noopener\">Visite el sitio web de AMMI<\/a><br \/><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/02\/20-Calgary_Canada.pdf\" target=\"_blank\" rel=\"noopener\">Descargar el cartel AMMI<\/a><\/p><p><strong>ECCMID \u00c1msterdam 2016<\/strong><\/p><p><a href=\"http:\/\/www.eccmid.org\/\" target=\"_blank\" rel=\"noopener\">Visite el sitio web del ECCMID<\/a><br \/><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2016\/04\/Global-PPS_ECCMID-2016_presentation-12april2016.pdf\" target=\"_blank\" rel=\"noopener\">Descargar la presentaci\u00f3n oral del ECCMID<\/a><br \/><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2022\/10\/BRCHenCVR-Global-PPS-LowRes.pdf\" target=\"_blank\" rel=\"noopener\">Descargar el folleto de Global-PPS ECCMID<\/a><\/p><p>Descargue los carteles del ECCMID:<\/p><ul><li><a href=\"https:\/\/www.global-pps.com\/es\/eccmid-2016_australia\/\" target=\"_blank\" rel=\"noopener\">ECCMID-2016_Australia<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2016\/04\/ECCMID-2016_Albania.pdf\" target=\"_blank\" rel=\"noopener\">ECCMID-2016_Albania<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/es\/eccmid_2016-e-poster-belgium_global-pps\/\" target=\"_blank\" rel=\"noopener\">ECCMID-2016_B\u00e9lgica<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2016\/04\/ECCMID-2016_CHILE.pdf\" target=\"_blank\" rel=\"noopener\">ECCMID-2016_CHILE<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2016\/04\/ECCMID-2016_Israel.pdf\" target=\"_blank\" rel=\"noopener\">ECCMID-2016_Israel<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2016\/04\/ECCMID-2016_England.pdf\" target=\"_blank\" rel=\"noopener\">ECCMID-2016_Inglaterra<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2016\/04\/ECCMID-2016_Japan.pdf\" target=\"_blank\" rel=\"noopener\">ECCMID-2016_Jap\u00f3n<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2016\/04\/ECCMID-2016_Kosovo.pdf\" target=\"_blank\" rel=\"noopener\">ECCMID-2016_Kosovo<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2016\/04\/ECCMID-2016_Nigeria.pdf\" target=\"_blank\" rel=\"noopener\">ECCMID-2016_Nigeria<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2016\/04\/ECCMID-2016_prophylactic-use_worldwide.pdf\" target=\"_blank\" rel=\"noopener\">ECCMID-2016_uso profil\u00e1ctico_en todo el mundo<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2016\/04\/ECCMID-2016_Russia.pdf\" target=\"_blank\" rel=\"noopener\">ECCMID-2016_Rusia<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2016\/04\/ECCMID-2016_Slovenia.pdf\" target=\"_blank\" rel=\"noopener\">ECCMID-2016_Eslovenia<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2016\/04\/ECCMID-2016_Serbia.pdf\" target=\"_blank\" rel=\"noopener\">ECCMID-2016_Serbia<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2016\/04\/ECCMID-2016_Slovenia_longitudinal.pdf\" target=\"_blank\" rel=\"noopener\">ECCMID-2016_Slovenia_longitudinal<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2016\/04\/ECCMID-2016_South-Africa.pdf\" target=\"_blank\" rel=\"noopener\">ECCMID-2016_South-Africa<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2016\/04\/ECCMID-2016_The-Netherlands.pdf\" target=\"_blank\" rel=\"noopener\">ECCMID-2016_Pa\u00edses Bajos<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2016\/04\/ECCMID-2016_USA.pdf\" target=\"_blank\" rel=\"noopener\">ECCMID-2016_USA<\/a><\/li><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2016\/04\/ECCMID-2016-pneumonia_worldwide.pdf\" target=\"_blank\" rel=\"noopener\">ECCMID-2016_neumon\u00eda_en_todo_el_mundo<\/a><\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-74612\" class=\"elementor-tab-title\" data-tab=\"12\" role=\"button\" aria-controls=\"elementor-tab-content-74612\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Congresos 2015<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-74612\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"12\" role=\"region\" aria-labelledby=\"elementor-tab-title-74612\"><p><strong>Foro mundial sobre HAI\/resistencia 2015<\/strong><\/p><ul><li>Vea en el siguiente v\u00eddeo una entrevista con el investigador principal del Global-PPS con motivo del 5<sup>th<\/sup>edici\u00f3n del Foro Mundial sobre IRAS\/Resistencia en junio de 2015.<\/li><li><a href=\"https:\/\/www.biomerieux.com\/en\/5th-world-hairesistance-forum\" target=\"_blank\" rel=\"noopener\">Lea el comunicado de prensa de bioM\u00e9rieux<\/a><\/li><\/ul><p><strong>Sociedad de Enfermedades Infecciosas de Am\u00e9rica 2015<\/strong><\/p><p><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/07\/IDWeek-poster-147_Global-PPS_17sept15.ppt.pdf\" target=\"_blank\" rel=\"noopener\">Cartel de la semana de la ID<\/a><br \/><a href=\"https:\/\/www.idsociety.org\/\" target=\"_blank\" rel=\"noopener\">Visite el sitio web de la IDSA<\/a><\/p><p><strong>Congreso B\u00e1ltico de Pediatr\u00eda 2015<\/strong><\/p><ul><li><a href=\"https:\/\/www.global-pps.com\/wp-content\/uploads\/2021\/07\/AB-Baltijas-Pediatru-kongress.pptx\" target=\"_blank\" rel=\"noopener\">Cartel BPC<\/a><\/li><li>Visite el\u00a0<a href=\"https:\/\/www.nuppi.eu\/en\/iii-baltic-paediatric-congress\" target=\"_blank\" rel=\"noopener\">sitio web<\/a><\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Congress materials The results of Global-PPS have been communicated during various congresses. Congresses 2026 ESCMID Global 2026, Munich The Global-PPS delegates presented four posters at ESCMID Global, sharing their latest research findings and insights: The global point prevalence survey (Global-PPS): trends of antimicrobial use in adult patients in the Philippines 2017-2024\u00a0\u2013 Presenter: Jemelyn Garcia Global [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ocean_post_layout":"full-screen","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"on","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"off","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","footnotes":""},"class_list":["post-13323","page","type-page","status-publish","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Congress materials - Global PPS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.global-pps.com\/es\/materiales-para-congresos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Congress materials - Global PPS\" \/>\n<meta property=\"og:description\" content=\"Congress materials The results of Global-PPS have been communicated during various congresses. Congresses 2026 ESCMID Global 2026, Munich The Global-PPS delegates presented four posters at ESCMID Global, sharing their latest research findings and insights: The global point prevalence survey (Global-PPS): trends of antimicrobial use in adult patients in the Philippines 2017-2024\u00a0\u2013 Presenter: Jemelyn Garcia Global [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.global-pps.com\/es\/materiales-para-congresos\/\" \/>\n<meta property=\"og:site_name\" content=\"Global PPS\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T15:14:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.global-pps.com\\\/congress-materials\\\/\",\"url\":\"https:\\\/\\\/www.global-pps.com\\\/congress-materials\\\/\",\"name\":\"Congress materials - Global PPS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.global-pps.com\\\/#website\"},\"datePublished\":\"2021-02-05T15:08:46+00:00\",\"dateModified\":\"2026-05-06T15:14:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.global-pps.com\\\/congress-materials\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.global-pps.com\\\/congress-materials\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.global-pps.com\\\/congress-materials\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.global-pps.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Congress materials\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.global-pps.com\\\/#website\",\"url\":\"https:\\\/\\\/www.global-pps.com\\\/\",\"name\":\"Global PPS\",\"description\":\"Sharing global knowledge\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.global-pps.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.global-pps.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.global-pps.com\\\/#organization\",\"name\":\"Global PPS\",\"url\":\"https:\\\/\\\/www.global-pps.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.global-pps.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.global-pps.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-GPPS-10-year-logo_scaled.png\",\"contentUrl\":\"https:\\\/\\\/www.global-pps.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-GPPS-10-year-logo_scaled.png\",\"width\":791,\"height\":771,\"caption\":\"Global PPS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.global-pps.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Material para congresos - Global PPS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.global-pps.com\/es\/materiales-para-congresos\/","og_locale":"es_ES","og_type":"article","og_title":"Congress materials - Global PPS","og_description":"Congress materials The results of Global-PPS have been communicated during various congresses. Congresses 2026 ESCMID Global 2026, Munich The Global-PPS delegates presented four posters at ESCMID Global, sharing their latest research findings and insights: The global point prevalence survey (Global-PPS): trends of antimicrobial use in adult patients in the Philippines 2017-2024\u00a0\u2013 Presenter: Jemelyn Garcia Global [&hellip;]","og_url":"https:\/\/www.global-pps.com\/es\/materiales-para-congresos\/","og_site_name":"Global PPS","article_modified_time":"2026-05-06T15:14:34+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.global-pps.com\/congress-materials\/","url":"https:\/\/www.global-pps.com\/congress-materials\/","name":"Material para congresos - Global PPS","isPartOf":{"@id":"https:\/\/www.global-pps.com\/#website"},"datePublished":"2021-02-05T15:08:46+00:00","dateModified":"2026-05-06T15:14:34+00:00","breadcrumb":{"@id":"https:\/\/www.global-pps.com\/congress-materials\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.global-pps.com\/congress-materials\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.global-pps.com\/congress-materials\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.global-pps.com\/"},{"@type":"ListItem","position":2,"name":"Congress materials"}]},{"@type":"WebSite","@id":"https:\/\/www.global-pps.com\/#website","url":"https:\/\/www.global-pps.com\/","name":"PPS mundial","description":"Compartir el conocimiento global","publisher":{"@id":"https:\/\/www.global-pps.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.global-pps.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.global-pps.com\/#organization","name":"PPS mundial","url":"https:\/\/www.global-pps.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.global-pps.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.global-pps.com\/wp-content\/uploads\/2024\/05\/cropped-GPPS-10-year-logo_scaled.png","contentUrl":"https:\/\/www.global-pps.com\/wp-content\/uploads\/2024\/05\/cropped-GPPS-10-year-logo_scaled.png","width":791,"height":771,"caption":"Global PPS"},"image":{"@id":"https:\/\/www.global-pps.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.global-pps.com\/es\/wp-json\/wp\/v2\/pages\/13323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.global-pps.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.global-pps.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.global-pps.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.global-pps.com\/es\/wp-json\/wp\/v2\/comments?post=13323"}],"version-history":[{"count":29,"href":"https:\/\/www.global-pps.com\/es\/wp-json\/wp\/v2\/pages\/13323\/revisions"}],"predecessor-version":[{"id":20900,"href":"https:\/\/www.global-pps.com\/es\/wp-json\/wp\/v2\/pages\/13323\/revisions\/20900"}],"wp:attachment":[{"href":"https:\/\/www.global-pps.com\/es\/wp-json\/wp\/v2\/media?parent=13323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}